{"id":4888,"date":"2021-10-20T17:43:39","date_gmt":"2021-10-20T17:43:39","guid":{"rendered":"https:\/\/davidobon.com\/?p=4888"},"modified":"2025-05-07T09:21:04","modified_gmt":"2025-05-07T09:21:04","slug":"libro-dinamicas-emergentes","status":"publish","type":"post","link":"https:\/\/davidobon.com\/es\/libro-dinamicas-emergentes\/","title":{"rendered":"Din\u00e1micas Emergentes"},"content":{"rendered":"<p><strong>La Arquitectura ante el Paradigma de la Complejidad<\/strong> (Spanish Edition)<\/p>\n\n\n\n<p>Este libro es, ante todo, una invitaci\u00f3n. Una invitaci\u00f3n a descubrir una nueva forma de ver y pensar el mundo que conlleva, a su vez, una nueva forma de ver y pensar la arquitectura. Con la ayuda de las ciencias de la complejidad y el pensamiento complejo de Edgar Morin, David Obon nos abre las puertas a un conocimiento que trasciende las barreras disciplinares. Se trata &nbsp;de un saber capaz de reconocer la multidimensionalidad de nuestra disciplina; de un saber que no simplifica, sino que reconecta, articula y clarifica. Un saber que nos habla de orden y de desorden pero, sobre todo, nos habla de creaci\u00f3n. Estos conocimientos han ido germinado en m\u00faltiples disciplinas hasta construir un nuevo paradigma emergente: el paradigma de la complejidad.<\/p>\n\n\n\n<p>A partir de los nuevos conceptos que articulan este paradigma, el autor hilvana un extraordinario relato en el que se revelan las profundas relaciones (relaciones sist\u00e9micas) entre la arquitectura y los diferentes niveles de organizaci\u00f3n vital: de la c\u00e9lula a la moderna sociedad red. Se trata, pues, de una s\u00edntesis te\u00f3rica radical. Radical, no en el sentido extremista del t\u00e9rmino; radical porque ata\u00f1e a la misma ra\u00edz (<em>radix<\/em>), a los verdaderos fundamentos, de la arquitectura.<\/p>\n\n\n\n<p>Estas p\u00e1ginas son tambi\u00e9n un ant\u00eddoto contra una de las caracter\u00edsticas \u2014 a menudo perversa\u2014, de nuestra moderna sociedad especializada: la fragmentaci\u00f3n y la parcelaci\u00f3n del saber. Porque ante una realidad que se hace cada vez m\u00e1s compleja necesitamos, hoy m\u00e1s que nunca, construir visiones integradoras que nos ayuden a orientar y clarificar nuestras formas de pensamiento y de acci\u00f3n. Este es el reto que aqu\u00ed afrontamos. Se trata de un reto porque la complejidad no se acaba nunca. As\u00ed que esperamos que tambi\u00e9n el lector acepte esta invitaci\u00f3n como un desaf\u00edo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.amazon.es\/DIN%C3%81MICAS-EMERGENTES-arquitectura-paradigma-complejidad\/dp\/8419050229\/ref=pd_lpo_sccl_1\/261-4486418-3585741?pd_rd_w=sdL7l&amp;content-id=amzn1.sym.dbff13a3-ec7b-4ab4-a8ad-e4356fa2bfdb&amp;pf_rd_p=dbff13a3-ec7b-4ab4-a8ad-e4356fa2bfdb&amp;pf_rd_r=KSSQNWB70QW0C7TZGTYM&amp;pd_rd_wg=9v27T&amp;pd_rd_r=b2c22640-b295-4a3f-afda-f1fbe915515b&amp;pd_rd_i=8419050229&amp;psc=1\" target=\"_blank\" rel=\"noopener\">GET THE BOOK<\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>La Arquitectura ante el Paradigma de la Complejidad (Spanish Edition) Este libro es, ante todo, una invitaci\u00f3n. Una invitaci\u00f3n a descubrir una nueva forma de ver y pensar el mundo que conlleva, a su vez, una nueva forma de ver y pensar la arquitectura. Con la ayuda de las ciencias de la complejidad y el&hellip;<\/p>","protected":false},"author":1,"featured_media":5301,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[73],"tags":[],"class_list":["post-4888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-books"],"acf":[],"_links":{"self":[{"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/posts\/4888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/comments?post=4888"}],"version-history":[{"count":9,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/posts\/4888\/revisions"}],"predecessor-version":[{"id":5642,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/posts\/4888\/revisions\/5642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/media\/5301"}],"wp:attachment":[{"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/media?parent=4888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/categories?post=4888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/davidobon.com\/es\/wp-json\/wp\/v2\/tags?post=4888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}